{"id":1117,"date":"2026-02-09T07:58:03","date_gmt":"2026-02-09T06:58:03","guid":{"rendered":"https:\/\/neues-mitteldeutschland.de\/?p=1117"},"modified":"2026-02-09T07:58:03","modified_gmt":"2026-02-09T06:58:03","slug":"ehrenamtsplattform-ehrensache-jetzt","status":"publish","type":"post","link":"https:\/\/neues-mitteldeutschland.de\/index.php\/2026\/02\/09\/ehrenamtsplattform-ehrensache-jetzt\/","title":{"rendered":"Ehrenamtsplattform ehrensache.jetzt"},"content":{"rendered":"<div class=\"layout_full block\">\n<p>Ehrenamtsplattform ehrensache.jetzt: Sinn stiften mit ehrenamtlichem Engagement<\/p>\n<div class=\"ce_text block\">\n<p>Freiwilliges Engagement liegt im Trend, st\u00e4rkt das gesellschaftliche Miteinander und hilft nicht nur anderen, sondern gibt auch dem eigenen Leben Bedeutung. \u201eEhrenamtliches Engagement bereitet Freude, da es Sinn stiftet und das eigene Wohlbefinden f\u00f6rdert \u2013 zugleich st\u00e4rkt es den sozialen Zusammenhalt und macht Gemeinschaft erlebbar\u201c, so Ron G\u00fcnther, neuer Koordinator der Ehrenamtsplattform ehrensache.jetzt f\u00fcr den Landkreis Zwickau.<\/p>\n<p>Die digitale Ehrenamtsplattform ehrensache.jetzt bietet Menschen in ganz Sachsen die M\u00f6glichkeit, ein Engagement zu finden, das zu ihren Interessen, F\u00e4higkeiten und zeitlichen M\u00f6glichkeiten passt. Gemeinn\u00fctzige Organisationen, Vereine und Initiativen k\u00f6nnen kostenfrei Inserate ver\u00f6ffentlichen und gezielt nach Unterst\u00fctzung suchen. Freiwillige nehmen direkt Kontakt zur Einsatzstelle auf, bei der sie sich engagieren m\u00f6chten. Ob regelm\u00e4\u00dfig oder punktuell \u2013 jede Stunde, jedes Gespr\u00e4ch und jede helfende Hand sind willkommen und st\u00e4rken das Miteinander.<\/p>\n<p>Die Ehrenamtsplattform ehrensache.jetzt wurde 2019 von der B\u00fcrgerstiftung Dresden entwickelt und richtet sich besonders an Engagierte, die einen flexiblen, modernen Zugang zum Ehrenamt suchen. Gleichzeitig soll sie einen Beitrag zur Attraktivit\u00e4t l\u00e4ndlicher R\u00e4ume leisten.<\/p>\n<p>Allein im Landkreis Zwickau sind derzeit 42 konkrete Ehrenamtsgesuche online auf lkzwickau.ehrensache.jetzt.<\/p>\n<p><strong>Mitmachen im Landkreis Zwickau: Aktuelle Gesuche<\/strong><\/p>\n<ul>\n<li>Der dfb Westsachsen e.V. sucht helfende H\u00e4nde f\u00fcr die Verteilung von Lebensmittelspenden in Meerane.<\/li>\n<li>Die GAB Gesellschaft f\u00fcr Arbeits- und Sozialf\u00f6rderung sucht engagierte Ehrenamtliche f\u00fcr das Sozialkaufhaus in Glauchau.<\/li>\n<li>Der Lebenshaus e.V. sucht eine einf\u00fchlsame Person, die einer alleinerziehenden Mutter mit zwei kleinen Kindern zur Seite stehen m\u00f6chte.<\/li>\n<li>Der Kinderschutzbund KV Zwickau e.V. sucht Telefonberater f\u00fcr das Kinder- und Jugendtelefon.<\/li>\n<li>Das Jugendamt des Landkreises Zwickaus sucht Personen f\u00fcr eine ehrenamtliche Vormundschaft.<\/li>\n<li>Der CV Zwickau e.V. sucht Unterst\u00fctzung im Altenpflegeheim bei der Freizeitgestaltung, Hauswirtschaft und Gartenpflege.<\/li>\n<\/ul>\n<p>Alle Inserate sind direkt auf www.ehrensache.jetzt einsehbar \u2013 ohne Registrierung, kostenfrei und regelm\u00e4\u00dfig aktualisiert. Der Koordinator Ron G\u00fcnther steht als Ansprechpartner telefonisch unter 0151 420 681 56 oder per Mail an guenther@buergerstiftung-dresden.de gern zur Verf\u00fcgung.<\/p>\n<p><em>Das Angebot ist in allen s\u00e4chsischen Landkreisen und der Stadt Dresden nutzbar. Das Projekt \u201eDigitale Ehrenamtsplattform f\u00fcr Sachsen\u201c wird gef\u00f6rdert durch das S\u00e4chsische Staatsministerium f\u00fcr Soziales und Gesellschaftlichen Zusammenhalt und finanziert aus Steuermitteln auf Grundlage des vom S\u00e4chsischen Landtag beschlossenen Haushalts.<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ehrenamtsplattform ehrensache.jetzt: Sinn stiften mit ehrenamtlichem Engagement Freiwilliges Engagement liegt im Trend, st\u00e4rkt das gesellschaftliche Miteinander und hilft nicht nur anderen, sondern gibt auch dem eigenen Leben Bedeutung. \u201eEhrenamtliches Engagement bereitet Freude, da es Sinn stiftet und das eigene Wohlbefinden f\u00f6rdert \u2013 zugleich st\u00e4rkt es den sozialen Zusammenhalt und macht Gemeinschaft erlebbar\u201c, so Ron G\u00fcnther, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":131,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-1117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meerane"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:57:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/1117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/comments?post=1117"}],"version-history":[{"count":1,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/1117\/revisions"}],"predecessor-version":[{"id":1118,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/1117\/revisions\/1118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media\/131"}],"wp:attachment":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media?parent=1117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/categories?post=1117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/tags?post=1117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}