{"id":557,"date":"2025-12-15T10:44:51","date_gmt":"2025-12-15T09:44:51","guid":{"rendered":"http:\/\/neuesmitteldeutschland.test\/?p=557"},"modified":"2026-04-28T16:55:53","modified_gmt":"2026-04-28T14:55:53","slug":"freilichttheater-waldenburg-e-v","status":"publish","type":"post","link":"https:\/\/neues-mitteldeutschland.de\/index.php\/2025\/12\/15\/freilichttheater-waldenburg-e-v\/","title":{"rendered":"Freilichttheater Waldenburg e.V."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"557\" class=\"elementor elementor-557\">\n\t\t\t\t<div class=\"elementor-element elementor-element-409ffd13 e-flex e-con-boxed e-con e-parent\" data-id=\"409ffd13\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6590f7a8 elementor-widget elementor-widget-text-editor\" data-id=\"6590f7a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"marktplatz_client_view_table\" class=\"row\"><div class=\"col-sm-12 col-md-7 col-xs-12\"><h1>Freilichttheater Waldenburg e.V.<\/h1><section id=\"marktplatz_client_view_contact_table\"><div id=\"marktplatz_client_view_contact_table_row\" class=\"row\"><div class=\"col-sm-4 col-xs-8\">Anschrift<\/div><div class=\"col-sm-8 col-xs-8\">Freilichttheater Waldenburg e.V.<br \/>Am Park 908396 Waldenburg<\/div><\/div><div id=\"marktplatz_client_view_contact_table_row\" class=\"row\"><div class=\"col-sm-4 col-xs-8\">Webseite<\/div><div class=\"col-sm-8 col-xs-8\"><a href=\"http:\/\/www.freilicht-theater.de\/\" target=\"_blank\" rel=\"noopener\">www.freilicht-theater.de\/ <\/a><\/div><\/div><div id=\"marktplatz_client_view_contact_table_description\" class=\"row\"><div class=\"col-sm-12 col-xs-12\">\u00a0<\/div><\/div><\/section><\/div><div class=\"col-sm-12 col-md-5 col-xs-12 map\"><iframe src=\"https:\/\/maps.google.com\/maps?hl=de&amp;q=Am+Park+9, Waldenburg+Freilichttheater+Waldenburg+e.V.&amp;ie=UTF8&amp;t=m&amp;vpsrc=0&amp;z=16&amp;output=embed\" width=\"100%\" height=\"300\" frameborder=\"1\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" data-mce-fragment=\"1\"><\/iframe><br \/><a href=\"http:\/\/maps.google.com\/maps?daddr=Am+Park+9,08396 Waldenburg+Freilichttheater+Waldenburg+e.V.&amp;ie=UTF8&amp;t=m&amp;vpsrc=0&amp;z=16&amp;source=embed\" target=\"_blank\" rel=\"noopener\">Gr\u00f6\u00dfere Kartenansicht<\/a><\/div><\/div><div class=\"row\"><div class=\"col-md-12 col-sm-12 col-xs-12\"><hr \/><\/div><\/div><div id=\"marktplatz_client_view_description\" class=\"row\"><div class=\"col-md-12 col-sm-12 col-xs-12\"><p><strong>\u00dcber uns<\/strong><br \/>Im Jahr 2003 gr\u00fcndete sich der Freilichttheater Waldenburg e.V. aus ehemaligen Darstellern der fr\u00fcheren St\u00fccke &#8211; die anf\u00e4nglich gut besuchten Karl-May-Festspiele der Naturb\u00fchne Waldenburg GmbH. Den 40 Akteuren vom Freilichttheater Waldenburg e.V. gelang mit dem Klassiker &#8222;Robin Hood&#8220; ein Neuanfang und hauchten der idyllisch gelegenen B\u00fchne wieder Leben ein. Mit der ca. 1000m\u00b2 bespielbaren Fl\u00e4che und den reichlich 500 zur Verf\u00fcgung stehenden Sitzpl\u00e4tzen geh\u00f6rt das Theater zu den gr\u00f6\u00dften, gleichzeitig aber auch idyllischsten B\u00fchnen Deutschlands.<br \/>Ohne bestehende finanzielle Mittel wurden Waffen, R\u00fcsten sowie alle n\u00f6tigen Kost\u00fcme und Requisiten selbst gebaut. Mit Ausschreibungen in Schulen und Zeitungsartikeln fanden sich neue Mitglieder&#8230; und der Verein wuchs. Am 10. Juli 2004, p\u00fcnktlich 17 Uhr, \u00f6ffnete sich zum ersten mal der Vorhang des Freilichttheater Waldenburg e.V.<br \/>Nat\u00fcrlich bleiben aber auch hier anforderungsgerechte Modernisierungen nicht aus. Die baulichen Entwicklungen an der B\u00fchne seit 2004 lassen sich am Besten mit dem Sprichwort &#8222;Rom wurde auch nicht an einem Tag erbaut&#8220; beschreiben. Angefangen hat alles in einem sehr &#8217;naturnahen&#8216; Zustand und erst nach und nach, durch st\u00e4ndige Bauunternehmungen der Mitglieder und weniger externer Helfer konnte die B\u00fchne in den Zustand gebracht werden, in dem diese heute zu bewundern ist.<br \/>ENDE KURZE VEREINSVORSTELLUNG<\/p><hr \/><section><div class=\"row\"><div class=\"col-md-6 col-sm-6 col-xs-12\"><p>Emal: <span id=\"cloak737c01726feeaf5365c0cf1b50f4adfa\"><a href=\"mailto:info@ftwmail.de\">info@ftwmail.de<\/a><\/span>\u00a0 Tel.: 0174\/2007794<\/p><\/div><\/div><\/section><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bad5726 e-con-full e-flex e-con e-child\" data-id=\"bad5726\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ac00077 e-grid e-con-full e-con e-child\" data-id=\"ac00077\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef3f4f9 elementor-widget elementor-widget-image\" data-id=\"ef3f4f9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"421\" src=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/gruppenbild.jpg\" class=\"attachment-large size-large wp-image-1412\" alt=\"\" srcset=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/gruppenbild.jpg 1024w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/gruppenbild-300x197.jpg 300w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/gruppenbild-768x506.jpg 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e57933d elementor-widget elementor-widget-image\" data-id=\"e57933d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"315\" src=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/auftritt-1024x504.jpg\" class=\"attachment-large size-large wp-image-1411\" alt=\"\" srcset=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/auftritt-1024x504.jpg 1024w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/auftritt-300x148.jpg 300w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/auftritt-768x378.jpg 768w, https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/2025\/12\/auftritt.jpg 1218w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2d6dc2 e-grid e-con-boxed e-con e-parent\" data-id=\"d2d6dc2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0212c98 elementor-widget elementor-widget-text-editor\" data-id=\"0212c98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Du wolltest schon immer mal auf der B\u00fchne stehen oder eine Kulisse errichten und gestalten? Du n\u00e4hst gerne und m\u00f6chtest Deine Kreationen einmal in einem Theaterst\u00fcck bestaunen? Du findest Stunts und B\u00fchnenkampf aufregend? Du m\u00f6chtest einmal als echte Prinzessin vor einem Publikum agieren? Dann bist Du bei uns genau richtig !<br \/>Durch unsere langj\u00e4hrigeErfahrung im Bereich Showkampf, B\u00fchnentechnik und darstellendes Spiel sind wir der ideale Ansprechpartner f\u00fcr Leute wie Dich. Das spricht Dich nicht an, weil Du nicht gern im Rampenlicht stehst? Kein Problem! Wir haben f\u00fcr jeden einen Platz vor oder hinter den Kulissen.Lust bekommen?????\u00a0 Sprich uns einfach an!!!!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4a0c25 elementor-widget elementor-widget-image\" data-id=\"c4a0c25\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/neues-mitteldeutschland.de\/wp-content\/uploads\/elementor\/thumbs\/764-rjm1uhogs3o8iwjdfd86953gry0rer34u8cvm6hi5o.jpg\" title=\"764\" alt=\"764\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Freilichttheater Waldenburg e.V. AnschriftFreilichttheater Waldenburg e.V.Am Park 908396 WaldenburgWebseitewww.freilicht-theater.de\/ \u00a0 Gr\u00f6\u00dfere Kartenansicht \u00dcber unsIm Jahr 2003 gr\u00fcndete sich der Freilichttheater Waldenburg e.V. aus ehemaligen Darstellern der fr\u00fcheren St\u00fccke &#8211; die anf\u00e4nglich gut besuchten Karl-May-Festspiele der Naturb\u00fchne Waldenburg GmbH. Den 40 Akteuren vom Freilichttheater Waldenburg e.V. gelang mit dem Klassiker &#8222;Robin Hood&#8220; ein Neuanfang und hauchten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1441,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,36],"tags":[],"class_list":["post-557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branchenverzeichnis","category-entertainment-musik"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:56:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":34,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"predecessor-version":[{"id":1945,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/557\/revisions\/1945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media\/1441"}],"wp:attachment":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}