{"id":907,"date":"2026-01-30T16:56:56","date_gmt":"2026-01-30T15:56:56","guid":{"rendered":"https:\/\/neues-mitteldeutschland.de\/?p=907"},"modified":"2026-01-30T16:56:56","modified_gmt":"2026-01-30T15:56:56","slug":"zoo-leipzig-koala-taufe-vollzogen-inala-heisst-erlingas-tochter","status":"publish","type":"post","link":"https:\/\/neues-mitteldeutschland.de\/index.php\/2026\/01\/30\/zoo-leipzig-koala-taufe-vollzogen-inala-heisst-erlingas-tochter\/","title":{"rendered":"Zoo Leipzig &#8211; Koala-Taufe vollzogen Inala hei\u00dft Erlingas Tochter"},"content":{"rendered":"<p>Mit einem besonders schmackhaften Strau\u00df Eukalyptus woodiwardi wurde heuteMorgen Erlingas (4) Tochter auf den Namen Inala getauft. Der Name Inala hat sich mit 44,7 Prozent der Stimmen knapp durchgesetzt. Auf dem zweiten Platz landete der Vorschlag Ruby mit 41,4 Prozent.<br \/>\n\u201eDank des Votings ist uns die finale Namensentscheidung abgenommen worden. Es wurden so viele kreative Namen eingereicht, dass es uns schwerfiel, allein die drei Kandidaten f\u00fcr das Voting auszuw\u00e4hlen. Vielen Dank an alle, die uns dabei unterst\u00fctzt haben. Inala passt hervorragend und bedeutet Frieden und steht in der Sprache der Aborigines f\u00fcr einen \u00b4friedlichen Ort\u00b4\u201c, erkl\u00e4rt Tierpfleger Philipp H\u00fcnemeyer.<br \/>\nDie Tochter von Youma (5) und Erlinga hat sich seit ihrer Geburt im Fr\u00fchsommer letzten Jahres bestens entwickelt. Sie zeigt sich zunehmend interessiert an ihrer Umgebung, wird lebhafter und kletterfreudiger und frisst bereits am Eukalyptus mit. Das Koalaweibchen ist als Erstgeb\u00e4rende eine \u00e4u\u00dferst liebevolle Mutter, die auch Vertrauen zu den Tierpflegern hat und zul\u00e4sst, dass diese Inala bereits allein wiegen. Aktuell bringt sie 1100 Gramm auf die Waage.<br \/>\nKoalas sind in Australien laut IUCN als gef\u00e4hrdet eingestuft. Lebensraumverlust durch Abholzung und Bebauung sowie die verheerenden Buschbr\u00e4nde infolge des Klimawandels setzen der Art stark zu. Die Population ist in den vergangenen Jahren dramatisch zur\u00fcckgegangen. \u201eJedes einzelne Jungtier, das in Zoos geboren wird, ist f\u00fcr das europ\u00e4ische Erhaltungszuchtprogramm dieser Art von enormer Bedeutung. Sie sind nicht nur Botschafter ihrer bedrohten Art, sondern bilden auch eine lebenswichtige Reservepopulation, die Hoffnung f\u00fcr den Erhalt dieser einzigartigen Tiere gibt\u201c, bewertet Seniorkurator Ariel Jacken den zweiten Zuchterfolg seit Beginn der Koalahaltung im Jahr 2016.<\/p>\n<p>Prof. J\u00f6rg Junhold<br \/>\nZoodirektor<\/p>\n<p>Bild Zoo Leipzig<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit einem besonders schmackhaften Strau\u00df Eukalyptus woodiwardi wurde heuteMorgen Erlingas (4) Tochter auf den Namen Inala getauft. Der Name Inala hat sich mit 44,7 Prozent der Stimmen knapp durchgesetzt. Auf dem zweiten Platz landete der Vorschlag Ruby mit 41,4 Prozent. \u201eDank des Votings ist uns die finale Namensentscheidung abgenommen worden. Es wurden so viele kreative [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":908,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leipzig"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:05:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/comments?post=907"}],"version-history":[{"count":1,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/907\/revisions"}],"predecessor-version":[{"id":909,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/posts\/907\/revisions\/909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media\/908"}],"wp:attachment":[{"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/media?parent=907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/categories?post=907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neues-mitteldeutschland.de\/index.php\/wp-json\/wp\/v2\/tags?post=907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}